{"id":14578,"date":"2020-12-04T08:54:22","date_gmt":"2020-12-04T11:54:22","guid":{"rendered":"http:\/\/sindesvdf.com.br\/news\/?p=14578"},"modified":"2020-12-04T08:54:22","modified_gmt":"2020-12-04T11:54:22","slug":"sindicato-agradece-empresas-que-fizeram-a-antecipacao-do-13o-salario-de-seus-empregados","status":"publish","type":"post","link":"https:\/\/sindesvdf.com.br\/news\/sindicato-agradece-empresas-que-fizeram-a-antecipacao-do-13o-salario-de-seus-empregados\/","title":{"rendered":"Sindicato agradece empresas que fizeram a antecipa\u00e7\u00e3o do 13\u00ba sal\u00e1rio de seus empregados"},"content":{"rendered":"<figure id=\"attachment_14579\" aria-describedby=\"caption-attachment-14579\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14579 size-full\" src=\"http:\/\/sindesvdf.com.br\/news\/wp-content\/uploads\/2020\/12\/13-salario.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/sindesvdf.com.br\/news\/wp-content\/uploads\/2020\/12\/13-salario.jpg 700w, https:\/\/sindesvdf.com.br\/news\/wp-content\/uploads\/2020\/12\/13-salario-300x171.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-14579\" class=\"wp-caption-text\">Vigilantes das empresas 5 Estrelas, Confederal e SEFIX receberam o seu 13\u00ba sal\u00e1rio antecipado.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 14pt;\">Em um momento dif\u00edcil como o que estamos vivendo, como a pandemia, a alta dos processos dos g\u00eaneros de primeira necessidade como g\u00e1s, luz, alimenta\u00e7\u00e3o, quando uma empresa faz a antecipa\u00e7\u00e3o do 13\u00ba de seus empregados \u00e9 um alento, pois \u00e9 certo que o vigilante est\u00e1 precisando desse refor\u00e7o do 13\u00ba sal\u00e1rio e quanto mais cedo chegar, melhor. E foi isso que fizeram as empresas 5 Estrelas, Confederal e SEFIX, driblando todas as dificuldades e pensando no social que tal atitude representa para os trabalhadores.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Por isso, esperamos que as demais empresas se sintam incentivadas por essa bela iniciativa e fa\u00e7am, tamb\u00e9m a antecipa\u00e7\u00e3o do 13\u00b0 sal\u00e1rio de seus empregados. O momento exige esses gestos de bondade e principalmente de reconhecimento pelo trabalho que os vigilantes realizam em seus postos de servi\u00e7o, no exerc\u00edcio da atividade, correndo todos os riscos inerentes \u00e0 profiss\u00e3o.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Estamos gratos e felizes pelos vigilantes que j\u00e1 receberam o seu 13\u00ba sal\u00e1rio antecipado e estamos prontos para comemorar pelos demais vigilantes das outras empresas.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Que venha a antecipa\u00e7\u00e3o.<\/span><\/p>\n<p class=\"wpf_wrapper\"><a class=\"print_link\" href=\"\" target=\"_blank\">Preparar para impress\u00e3o<\/a><\/p><!-- .wpf_wrapper -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Em um momento dif\u00edcil como o que estamos vivendo, como a pandemia, a alta dos processos dos g\u00eaneros de&hellip; <\/p>\n","protected":false},"author":4,"featured_media":14579,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,101],"tags":[],"class_list":["post-14578","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-olho-vivo"],"jetpack_featured_media_url":"https:\/\/sindesvdf.com.br\/news\/wp-content\/uploads\/2020\/12\/13-salario.jpg","_links":{"self":[{"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/posts\/14578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/comments?post=14578"}],"version-history":[{"count":1,"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/posts\/14578\/revisions"}],"predecessor-version":[{"id":14580,"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/posts\/14578\/revisions\/14580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/media\/14579"}],"wp:attachment":[{"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/media?parent=14578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/categories?post=14578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/tags?post=14578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}