{"id":7950,"date":"2017-07-05T11:50:01","date_gmt":"2017-07-05T14:50:01","guid":{"rendered":"http:\/\/sindesvdf.com.br\/news\/?p=7950"},"modified":"2017-08-04T11:19:26","modified_gmt":"2017-08-04T14:19:26","slug":"oposicao-protesta-mas-senado-aprova-urgencia-da-reforma-trabalhista","status":"publish","type":"post","link":"https:\/\/sindesvdf.com.br\/news\/oposicao-protesta-mas-senado-aprova-urgencia-da-reforma-trabalhista\/","title":{"rendered":"Oposi\u00e7\u00e3o protesta, mas Senado aprova urg\u00eancia da reforma trabalhista"},"content":{"rendered":"<h4 id=\"link_lead\" style=\"text-align: center;\"><em>Com 46 votos a favor e 19 contra, o plen\u00e1rio do Senado aprovou na tarde desta ter\u00e7a-feira (4) requerimento de urg\u00eancia para vota\u00e7\u00e3o do projeto de \u201creforma\u201d trabalhista, o que ocorrer\u00e1 na semana que vem, provavelmente no dia 12. O presidente da Casa, Eun\u00edcio Oliveira (PMDB-CE), informou que o PLC 38 entrar\u00e1 na ordem do dia de amanh\u00e3, para discuss\u00e3o.<\/em><\/h4>\n<p>&nbsp;<\/p>\n<div class=\"imagem-box imagem-box-1\">\n<figure style=\"width: 350px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"\" title=\"Senadora Vanessa Grazziotin (PCdoB-AM) e a oposi\u00e7\u00e3o protestaram e pediram a suspens\u00e3o da tramita\u00e7\u00e3o do projeto\" src=\"http:\/\/imagem.vermelho.org.br\/biblioteca\/vanessa_na_tribuna_do_senado111006.jpg\" alt=\"\" width=\"350\" height=\"246\" \/><figcaption class=\"wp-caption-text\"><span style=\"font-size: 12px;\">Senadora Vanessa Grazziotin (PCdoB-AM) e a oposi\u00e7\u00e3o protestaram e pediram a suspens\u00e3o da tramita\u00e7\u00e3o do projeto<\/span><\/figcaption><\/figure>\n<\/div>\n<p>A oposi\u00e7\u00e3o insistiu na suspens\u00e3o do projeto, argumentando que o presidente Michel Temer est\u00e1 sendo denunciado pela Procuradoria-Geral da Rep\u00fablica. <em>\u201cEle pode n\u00e3o ser presidente daqui a 15 dias. Estamos discutindo uma reforma trabalhista aceitando um acordo com esse presidente\u201d<\/em>, disse o l\u00edder do PT no Senado, Lindbergh Farias (RJ). A bancada governista conseguiu manter o texto como aprovado na C\u00e2mara, para agilizar a tramita\u00e7\u00e3o, e afirma que Temer mandar\u00e1 medida provis\u00f3ria <em>\u201ccorrigindo\u201d<\/em> alguns pontos.<\/p>\n<p>Segundo Vanessa Grazziotin (PCdoB-AM), h\u00e1 uma <em>\u201cunanimidade\u201d<\/em> na Casa quanto \u00e0 necessidade de promover mudan\u00e7as no texto.<em> \u201cN\u00e3o h\u00e1 uma alma neste Senado Federal, uma senadora, um senador, que tenha coragem de defender o projeto na \u00edntegra\u201d<\/em>, afirmou.<\/p>\n<p>Ela voltou a criticar o relator nas comiss\u00f5es de Assuntos Econ\u00f4micos e de Assuntos Sociais, Ricardo Ferra\u00e7o (PSDB-ES), que<em> \u201csimplesmente abriu m\u00e3o de sua tarefa e passou a recomendar ao presidente da Rep\u00fablica que promovesse alguns vetos e editasse medidas provis\u00f3rias\u201d<\/em>. Segundo a senadora, na carta-compromisso encaminhada na semana passada Temer <em>\u201capenas enrola\u201d<\/em>.<\/p>\n<p><em>\u201cEsse projeto n\u00e3o vai gerar um emprego a mais\u201d<\/em>, disse Lindbergh.<em> \u201cCriamos 22 milh\u00f5es de empregos com essa legisla\u00e7\u00e3o\u201d<\/em>, acrescentou. <em>\u201cS\u00f3 a base do governo apresentou 85 emendas\u201d<\/em>, lembrou Paulo Paim (PT-RS).<\/p>\n<p style=\"text-align: right;\"><span style=\"color: #ff0000;\"><em>Fonte: Rede Brasil Atual<\/em><\/span><\/p>\n<p class=\"wpf_wrapper\"><a class=\"print_link\" href=\"\" target=\"_blank\">Preparar para impress\u00e3o<\/a><\/p><!-- .wpf_wrapper -->","protected":false},"excerpt":{"rendered":"<p>Com 46 votos a favor e 19 contra, o plen\u00e1rio do Senado aprovou na tarde desta ter\u00e7a-feira (4) requerimento de&hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[112],"tags":[],"class_list":["post-7950","post","type-post","status-publish","format-standard","hentry","category-as-reformas-do-mal"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/posts\/7950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/comments?post=7950"}],"version-history":[{"count":5,"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/posts\/7950\/revisions"}],"predecessor-version":[{"id":7953,"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/posts\/7950\/revisions\/7953"}],"wp:attachment":[{"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/media?parent=7950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/categories?post=7950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/tags?post=7950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}