{"id":8003,"date":"2017-07-12T13:21:10","date_gmt":"2017-07-12T16:21:10","guid":{"rendered":"http:\/\/sindesvdf.com.br\/news\/?p=8003"},"modified":"2017-08-04T11:18:25","modified_gmt":"2017-08-04T14:18:25","slug":"senado-faz-das-leis-trabalhistas-instrumentos-de-protecao-as-empresas","status":"publish","type":"post","link":"https:\/\/sindesvdf.com.br\/news\/senado-faz-das-leis-trabalhistas-instrumentos-de-protecao-as-empresas\/","title":{"rendered":"Senado faz das leis trabalhistas instrumentos de prote\u00e7\u00e3o \u00e0s empresas"},"content":{"rendered":"<div class=\"nitfSubtitle\">Para diretor t\u00e9cnico do Dieese, cen\u00e1rio ainda \u00e9 revers\u00edvel, por\u00e9m movimento sindical ter\u00e1 que &#8220;organizar o ch\u00e3o das f\u00e1bricas&#8221;<\/div>\n<div id=\"viewlet-below-content-title\">\n<div id=\"plone-document-byline\" class=\"documentByLine\"><span class=\"documentAuthor\">por\u00a0Reda\u00e7\u00e3o RBA\u00a0<\/span><span class=\"documentPublished\">publicado\u00a012\/07\/2017<\/span><\/div>\n<\/div>\n<div id=\"viewlet-above-content-body\"><\/div>\n<div id=\"content-core\">\n<div class=\"tile-rights\">RIBS\/FACEBOOK<\/div>\n<div class=\"newsImageContainer\"><a id=\"parent-fieldname-image\" class=\"link-overlay\" rel=\"#pb_1\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"newsImage nitf lazyloaded\" title=\"clt.jpg\" src=\"http:\/\/www.redebrasilatual.com.br\/trabalho\/2017\/07\/senado-faz-das-leis-trabalhistas-instrumentos-de-protecao-as-empresas\/clt.jpg\/image_preview\" alt=\"clt.jpg\" width=\"360\" height=\"226\" data-src=\"http:\/\/www.redebrasilatual.com.br\/trabalho\/2017\/07\/senado-faz-das-leis-trabalhistas-instrumentos-de-protecao-as-empresas\/clt.jpg\/image_preview\" \/><\/p>\n<p class=\"discreet\">Senado aprovou, nesta ter\u00e7a feira, cerca de 300 novas mudan\u00e7as na CLT que retiram direitos trabalhistas<\/p>\n<\/div>\n<div>\n<p>S\u00e3o Paulo \u2013 Para o diretor t\u00e9cnico do Dieese, Clemente Ganz L\u00facio,\u00a0a\u00a0<a class=\"internal-link\" title=\"\" href=\"http:\/\/www.redebrasilatual.com.br\/politica\/2017\/07\/senado-aprova-o-projeto-de-reforma-trabalhista-sem-alteracoes\" target=\"_blank\" rel=\"noopener\">aprova\u00e7\u00e3o no Senado da reforma trabalhista<\/a>, nesta ter\u00e7a-feira (11), demonstra uma &#8220;estrat\u00e9gia de sucesso do governo&#8221;, pois a partir de agora, a legisla\u00e7\u00e3o trabalhista ter\u00e1 um novo protegido. &#8220;Com a mudan\u00e7a de 300 itens nas leis referentes ao trabalho, elas\u00a0viraram uma grande prote\u00e7\u00e3o \u00e0s empresas&#8221;, afirma, em entrevista\u00a0\u00e0\u00a0<strong>R\u00e1dio Brasil Atual<\/strong>, hoje (12).<\/p>\n<p>Clemente diz n\u00e3o acreditar que as mudan\u00e7as sejam definitivas, sem possibilidade de serem revertidas. Segundo ele, a reforma trabalhista aprovada pelo Senado \u00e9 uma &#8220;agenda aberta&#8221; para os movimentos sindicais trabalharem daqui para frente.<\/p>\n<p>&#8220;Haver\u00e1 uma disputa ainda pela frente para for\u00e7ar o presidente a vetar alguma parte do projeto, depois ser\u00e1 na Justi\u00e7a do Trabalho, no Supremo Tribunal Federal e, principalmente, no ch\u00e3o das f\u00e1bricas, atrav\u00e9s da organiza\u00e7\u00e3o sindical&#8221;, diz o diretor t\u00e9cnico do Dieese.<\/p>\n<\/div>\n<\/div>\n<p class=\"wpf_wrapper\"><a class=\"print_link\" href=\"\" target=\"_blank\">Preparar para impress\u00e3o<\/a><\/p><!-- .wpf_wrapper -->","protected":false},"excerpt":{"rendered":"<p>Para diretor t\u00e9cnico do Dieese, cen\u00e1rio ainda \u00e9 revers\u00edvel, por\u00e9m movimento sindical ter\u00e1 que &#8220;organizar o ch\u00e3o das f\u00e1bricas&#8221; por\u00a0Reda\u00e7\u00e3o&hellip; <\/p>\n","protected":false},"author":1,"featured_media":8004,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[112],"tags":[],"class_list":["post-8003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-as-reformas-do-mal"],"jetpack_featured_media_url":"https:\/\/sindesvdf.com.br\/news\/wp-content\/uploads\/2017\/07\/descartaval.jpg","_links":{"self":[{"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/posts\/8003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/comments?post=8003"}],"version-history":[{"count":1,"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/posts\/8003\/revisions"}],"predecessor-version":[{"id":8005,"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/posts\/8003\/revisions\/8005"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/media\/8004"}],"wp:attachment":[{"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/media?parent=8003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/categories?post=8003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindesvdf.com.br\/news\/wp-json\/wp\/v2\/tags?post=8003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}